{"id":1536,"date":"2025-04-04T10:47:18","date_gmt":"2025-04-04T10:47:18","guid":{"rendered":"https:\/\/voruporbadehotel.dk\/?page_id=1536"},"modified":"2025-04-04T18:07:11","modified_gmt":"2025-04-04T18:07:11","slug":"digital-visiting-card","status":"publish","type":"page","link":"https:\/\/voruporbadehotel.dk\/en\/digital-visit-kort\/","title":{"rendered":"digital Visit Kort"},"content":{"rendered":"<div id=\"fws_6a5761be23a83\"  data-column-margin=\"default\" data-midnight=\"dark\" data-top-percent=\"10%\"  class=\"wpb_row vc_row-fluid vc_row  bottom_padding_phone_25pct\"  style=\"padding-top: calc(100vw * 0.10); padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-4 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-8 wpb_column column_container vc_column_container col right_padding_desktop_8pct\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"nectar-split-heading  font_size_70px text_direction_ltr\" data-align=\"default\" data-m-align=\"inherit\" data-text-effect=\"default\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"0\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"\" data-custom-font-size=\"true\" style=\"font-size: 70px; line-height: 75.6px;\"><h2 style=\" color: #284596;\">My digital business card<\/h2><\/div><div class=\"nectar-responsive-text font_size_tablet_1em font_size_phone_17px font_line_height_1-6 nectar-link-underline-effect\"><p class=\"p1\">Click the link below for all my contact details.<br \/>\nLet's keep in touch.<\/p>\n<\/div><div id=\"fws_6a5761be2475c\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column no-extra-padding force-desktop-text-align-right force-phone-text-align-left inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<a class=\"nectar-button large regular accent-color has-icon  regular-button\"  role=\"button\" style=\"margin-top: 40px; color: #d6e8ba; \"  href=\"https:\/\/vcard.link\/card\/IZfm.vcf\" data-color-override=\"false\" data-hover-color-override=\"false\" data-hover-text-color-override=\"#fff\"><span>Get business cards<\/span><i style=\"color: #d6e8ba;\"  class=\"icon-button-arrow\"><\/i><\/a>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>","protected":false},"excerpt":{"rendered":"Mit digitale visit kortTryk p\u00e5 linket herunder, s\u00e5 har du alle mine kontaktoplysninger. Lad os holde kontakten. Hent...","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1536","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/voruporbadehotel.dk\/en\/wp-json\/wp\/v2\/pages\/1536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voruporbadehotel.dk\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/voruporbadehotel.dk\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/voruporbadehotel.dk\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/voruporbadehotel.dk\/en\/wp-json\/wp\/v2\/comments?post=1536"}],"version-history":[{"count":0,"href":"https:\/\/voruporbadehotel.dk\/en\/wp-json\/wp\/v2\/pages\/1536\/revisions"}],"wp:attachment":[{"href":"https:\/\/voruporbadehotel.dk\/en\/wp-json\/wp\/v2\/media?parent=1536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}